{"id":32355,"date":"2024-09-09T17:58:18","date_gmt":"2024-09-09T17:58:18","guid":{"rendered":"https:\/\/nativoqueretaro.mx\/?p=32355"},"modified":"2024-09-09T17:58:18","modified_gmt":"2024-09-09T17:58:18","slug":"la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue","status":"publish","type":"post","link":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/","title":{"rendered":"La colaboraci\u00f3n de la poblaci\u00f3n es relevante para las acciones de prevenci\u00f3n y control del dengue"},"content":{"rendered":"<p>La Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro exhorta a la poblaci\u00f3n a adoptar y reforzar medidas preventivas ante el incremento en el n\u00famero de casos de dengue en M\u00e9xico. Es fundamental eliminar todo tipo de criaderos de mosquitos, protegerse de las picaduras y solicitar atenci\u00f3n m\u00e9dica oportuna en caso de presentar s\u00edntomas.<\/p>\n<p>&nbsp;<\/p>\n<p>Con informaci\u00f3n al 5 de septiembre de 2024, se han registrado 752 casos positivos en el estado de Quer\u00e9taro. Se trata de 453 mujeres y 299 hombres, dos con domicilio en el municipio de Amealco de Bonfil, 66 en Arroyo Seco, dos en Cadereyta de Montes, dos en Col\u00f3n, seis en Corregidora, dos en El Marqu\u00e9s, uno en Ezequiel Montes, 108 en Jalpan de Serra, cinco en Landa de Matamoros, 158 en Pe\u00f1amiller, 256 en Quer\u00e9taro y 144 en Tolim\u00e1n. Se registraron dos defunciones, una en el municipio de Pe\u00f1amiller y una en Quer\u00e9taro.<\/p>\n<p>&nbsp;<\/p>\n<p>De los 752 casos, 660 casos son dengue no grave, 83 casos con dengue con signos de alarma y nueve casos con dengue grave. A nivel nacional, al 2 de septiembre se han reportado 47 mil 595 casos positivos de dengue y 132 defunciones por esta causa.<\/p>\n<p>&nbsp;<\/p>\n<p>En el per\u00edodo de enero a agosto de 2024, las acciones de control de esta enfermedad que realizaron las y los trabajadores de las brigadas de vectores trabajaron en 67 localidades, teniendo un concentrado de 34.5 toneladas de cacharros.<\/p>\n<p>&nbsp;<\/p>\n<p>De la misma forma, se ejecutaron acciones de control larvario colocando abate en 36 mil 774 casas y 110 mil 342 dep\u00f3sitos, protegiendo a 100 mil 309 habitantes; se efectu\u00f3 rociado intradomiciliario a ocho mil 499 casas, protegiendo a 40 mil 880 habitantes; se realiz\u00f3 fumigaci\u00f3n espacial en diez mil 537 hect\u00e1reas; se colocaron 20 mil 648 ovitrampas en localidades de riesgo, con recolecci\u00f3n de 158 mil 80 huevecillos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro exhorta a la poblaci\u00f3n a adoptar y reforzar medidas preventivas ante el incremento en el n\u00famero de casos de dengue en M\u00e9xico. Es fundamental eliminar todo tipo de criaderos de mosquitos, protegerse de las picaduras y solicitar atenci\u00f3n m\u00e9dica oportuna en caso de presentar s\u00edntomas. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[4,3,9,6,5],"tags":[],"class_list":["post-32355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corregidora","category-el-marques","category-portada","category-queretaro-capital-e-industria","category-san-juan-del-rio","entry","has-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La colaboraci\u00f3n de la poblaci\u00f3n es relevante para las acciones de prevenci\u00f3n y control del dengue - Nativo Quer\u00e9taro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La colaboraci\u00f3n de la poblaci\u00f3n es relevante para las acciones de prevenci\u00f3n y control del dengue - Nativo Quer\u00e9taro\" \/>\n<meta property=\"og:description\" content=\"La Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro exhorta a la poblaci\u00f3n a adoptar y reforzar medidas preventivas ante el incremento en el n\u00famero de casos de dengue en M\u00e9xico. Es fundamental eliminar todo tipo de criaderos de mosquitos, protegerse de las picaduras y solicitar atenci\u00f3n m\u00e9dica oportuna en caso de presentar s\u00edntomas. &nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/\" \/>\n<meta property=\"og:site_name\" content=\"Nativo Quer\u00e9taro\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-09T17:58:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2024\/09\/71_273_45325_1685037933_3_0609_SESA_PREVENCION_Y_CONTROL_DENGUE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"702\" \/>\n\t<meta property=\"og:image:height\" content=\"1342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NativoQro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NativoQro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/\"},\"author\":{\"name\":\"NativoQro\",\"@id\":\"https:\/\/nativoqueretaro.mx\/#\/schema\/person\/9cb2d9bff62be7a0a4a39066c9eac822\"},\"headline\":\"La colaboraci\u00f3n de la poblaci\u00f3n es relevante para las acciones de prevenci\u00f3n y control del dengue\",\"datePublished\":\"2024-09-09T17:58:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/\"},\"wordCount\":314,\"publisher\":{\"@id\":\"https:\/\/nativoqueretaro.mx\/#organization\"},\"image\":{\"@id\":\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2024\/09\/71_273_45325_1685037933_3_0609_SESA_PREVENCION_Y_CONTROL_DENGUE.jpg\",\"articleSection\":[\"Corregidora\",\"El Marqu\u00e9s\",\"Portada\",\"Quer\u00e9taro Capital e Industria\",\"San Juan del R\u00edo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/\",\"url\":\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/\",\"name\":\"La colaboraci\u00f3n de la poblaci\u00f3n es relevante para las acciones de prevenci\u00f3n y control del dengue - Nativo Quer\u00e9taro\",\"isPartOf\":{\"@id\":\"https:\/\/nativoqueretaro.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2024\/09\/71_273_45325_1685037933_3_0609_SESA_PREVENCION_Y_CONTROL_DENGUE.jpg\",\"datePublished\":\"2024-09-09T17:58:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#primaryimage\",\"url\":\"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2024\/09\/71_273_45325_1685037933_3_0609_SESA_PREVENCION_Y_CONTROL_DENGUE.jpg\",\"contentUrl\":\"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2024\/09\/71_273_45325_1685037933_3_0609_SESA_PREVENCION_Y_CONTROL_DENGUE.jpg\",\"width\":702,\"height\":1342},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nativoqueretaro.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La colaboraci\u00f3n de la poblaci\u00f3n es relevante para las acciones de prevenci\u00f3n y control del dengue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nativoqueretaro.mx\/#website\",\"url\":\"https:\/\/nativoqueretaro.mx\/\",\"name\":\"Nativo Quer\u00e9taro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nativoqueretaro.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nativoqueretaro.mx\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nativoqueretaro.mx\/#organization\",\"name\":\"Nativo Quer\u00e9taro\",\"url\":\"https:\/\/nativoqueretaro.mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nativoqueretaro.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2025\/01\/NATIVO_QRO_white.svg\",\"contentUrl\":\"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2025\/01\/NATIVO_QRO_white.svg\",\"caption\":\"Nativo Quer\u00e9taro\"},\"image\":{\"@id\":\"https:\/\/nativoqueretaro.mx\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/nativoqueretaro.mx\/#\/schema\/person\/9cb2d9bff62be7a0a4a39066c9eac822\",\"name\":\"NativoQro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nativoqueretaro.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0574151f0584a2a8056a6d87f37cd6abc6c709a951c8e822eb1ab470a5022bc5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0574151f0584a2a8056a6d87f37cd6abc6c709a951c8e822eb1ab470a5022bc5?s=96&d=mm&r=g\",\"caption\":\"NativoQro\"},\"url\":\"https:\/\/nativoqueretaro.mx\/index.php\/author\/nativoadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La colaboraci\u00f3n de la poblaci\u00f3n es relevante para las acciones de prevenci\u00f3n y control del dengue - Nativo Quer\u00e9taro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/","og_locale":"es_MX","og_type":"article","og_title":"La colaboraci\u00f3n de la poblaci\u00f3n es relevante para las acciones de prevenci\u00f3n y control del dengue - Nativo Quer\u00e9taro","og_description":"La Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro exhorta a la poblaci\u00f3n a adoptar y reforzar medidas preventivas ante el incremento en el n\u00famero de casos de dengue en M\u00e9xico. Es fundamental eliminar todo tipo de criaderos de mosquitos, protegerse de las picaduras y solicitar atenci\u00f3n m\u00e9dica oportuna en caso de presentar s\u00edntomas. &nbsp; [&hellip;]","og_url":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/","og_site_name":"Nativo Quer\u00e9taro","article_published_time":"2024-09-09T17:58:18+00:00","og_image":[{"width":702,"height":1342,"url":"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2024\/09\/71_273_45325_1685037933_3_0609_SESA_PREVENCION_Y_CONTROL_DENGUE.jpg","type":"image\/jpeg"}],"author":"NativoQro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"NativoQro","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#article","isPartOf":{"@id":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/"},"author":{"name":"NativoQro","@id":"https:\/\/nativoqueretaro.mx\/#\/schema\/person\/9cb2d9bff62be7a0a4a39066c9eac822"},"headline":"La colaboraci\u00f3n de la poblaci\u00f3n es relevante para las acciones de prevenci\u00f3n y control del dengue","datePublished":"2024-09-09T17:58:18+00:00","mainEntityOfPage":{"@id":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/"},"wordCount":314,"publisher":{"@id":"https:\/\/nativoqueretaro.mx\/#organization"},"image":{"@id":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#primaryimage"},"thumbnailUrl":"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2024\/09\/71_273_45325_1685037933_3_0609_SESA_PREVENCION_Y_CONTROL_DENGUE.jpg","articleSection":["Corregidora","El Marqu\u00e9s","Portada","Quer\u00e9taro Capital e Industria","San Juan del R\u00edo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/","url":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/","name":"La colaboraci\u00f3n de la poblaci\u00f3n es relevante para las acciones de prevenci\u00f3n y control del dengue - Nativo Quer\u00e9taro","isPartOf":{"@id":"https:\/\/nativoqueretaro.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#primaryimage"},"image":{"@id":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#primaryimage"},"thumbnailUrl":"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2024\/09\/71_273_45325_1685037933_3_0609_SESA_PREVENCION_Y_CONTROL_DENGUE.jpg","datePublished":"2024-09-09T17:58:18+00:00","breadcrumb":{"@id":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#primaryimage","url":"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2024\/09\/71_273_45325_1685037933_3_0609_SESA_PREVENCION_Y_CONTROL_DENGUE.jpg","contentUrl":"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2024\/09\/71_273_45325_1685037933_3_0609_SESA_PREVENCION_Y_CONTROL_DENGUE.jpg","width":702,"height":1342},{"@type":"BreadcrumbList","@id":"https:\/\/nativoqueretaro.mx\/index.php\/2024\/09\/09\/la-colaboracion-de-la-poblacion-es-relevante-para-las-acciones-de-prevencion-y-control-del-dengue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nativoqueretaro.mx\/"},{"@type":"ListItem","position":2,"name":"La colaboraci\u00f3n de la poblaci\u00f3n es relevante para las acciones de prevenci\u00f3n y control del dengue"}]},{"@type":"WebSite","@id":"https:\/\/nativoqueretaro.mx\/#website","url":"https:\/\/nativoqueretaro.mx\/","name":"Nativo Quer\u00e9taro","description":"","publisher":{"@id":"https:\/\/nativoqueretaro.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nativoqueretaro.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nativoqueretaro.mx\/#organization","name":"Nativo Quer\u00e9taro","url":"https:\/\/nativoqueretaro.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nativoqueretaro.mx\/#\/schema\/logo\/image\/","url":"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2025\/01\/NATIVO_QRO_white.svg","contentUrl":"https:\/\/nativoqueretaro.mx\/wp-content\/uploads\/2025\/01\/NATIVO_QRO_white.svg","caption":"Nativo Quer\u00e9taro"},"image":{"@id":"https:\/\/nativoqueretaro.mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nativoqueretaro.mx\/#\/schema\/person\/9cb2d9bff62be7a0a4a39066c9eac822","name":"NativoQro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nativoqueretaro.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0574151f0584a2a8056a6d87f37cd6abc6c709a951c8e822eb1ab470a5022bc5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0574151f0584a2a8056a6d87f37cd6abc6c709a951c8e822eb1ab470a5022bc5?s=96&d=mm&r=g","caption":"NativoQro"},"url":"https:\/\/nativoqueretaro.mx\/index.php\/author\/nativoadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/nativoqueretaro.mx\/index.php\/wp-json\/wp\/v2\/posts\/32355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativoqueretaro.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativoqueretaro.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativoqueretaro.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nativoqueretaro.mx\/index.php\/wp-json\/wp\/v2\/comments?post=32355"}],"version-history":[{"count":0,"href":"https:\/\/nativoqueretaro.mx\/index.php\/wp-json\/wp\/v2\/posts\/32355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativoqueretaro.mx\/index.php\/wp-json\/wp\/v2\/media\/32357"}],"wp:attachment":[{"href":"https:\/\/nativoqueretaro.mx\/index.php\/wp-json\/wp\/v2\/media?parent=32355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativoqueretaro.mx\/index.php\/wp-json\/wp\/v2\/categories?post=32355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativoqueretaro.mx\/index.php\/wp-json\/wp\/v2\/tags?post=32355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}